{"id":10644,"date":"2025-09-06T11:43:23","date_gmt":"2025-09-06T09:43:23","guid":{"rendered":"https:\/\/www.autoteile-markt.de\/blog\/?p=10644"},"modified":"2025-09-06T11:43:24","modified_gmt":"2025-09-06T09:43:24","slug":"abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten","status":"publish","type":"post","link":"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/","title":{"rendered":"Abgasuntersuchung beim Auto \u2013 Was Sie vor der Pr\u00fcfung wissen sollten!"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img  title=\"Abgasuntersuchung beim Auto \u2013 Was Sie vor der Pr\u00fcfung wissen sollten!\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Titelbild-Abgasuntersuchung-AU.jpg\"  alt=\"Titelbild-Abgasuntersuchung-AU Abgasuntersuchung beim Auto \u2013 Was Sie vor der Pr\u00fcfung wissen sollten!\"  class=\"wp-image-10645\" srcset=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Titelbild-Abgasuntersuchung-AU.jpg 1000w, https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Titelbild-Abgasuntersuchung-AU-300x200.jpg 300w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">\u00a9Foto: weyo\/depositphotos.com<\/figcaption><\/figure>\n\n\n\n<p>Die Abgasuntersuchung beim Auto dient dazu, den Schadstoffgehalt der Abgase zu pr\u00fcfen. Diese m\u00fcssen innerhalb gesetzlicher Grenzwerte liegen. Das ist wichtig, damit besonders \u00e4ltere Fahrzeuge nicht zur sprichw\u00f6rtlichen \u201eDreckschleuder\u201c werden. Bei Versto\u00df gegen die Pflicht zur Abgasuntersuchung drohen Bu\u00dfgelder und Punkte in Flensburg. Wir erkl\u00e4ren in diesem Ratgeber Wissenswertes zur Abgasuntersuchung und verraten, welche Kosten dadurch auf Sie zukommen und wie Sie Ihr Fahrzeug richtig vorbereiten.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/#Welchen_Zweck_hat_die_Abgasuntersuchung_AU_beim_Auto\" >Welchen Zweck hat die Abgasuntersuchung (AU) beim Auto?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/#Wie_laeuft_eine_Abgasuntersuchung_beim_Auto_ab\" >Wie l\u00e4uft eine Abgasuntersuchung beim Auto ab?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/#Vorbereitung_zur_AU_%E2%80%93_Schritt_fuer_Schritt_Anleitung\" >Vorbereitung zur AU \u2013 Schritt f\u00fcr Schritt Anleitung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/#Welche_Kosten_fallen_fuer_die_Reparatur_der_Abgasanlage_in_der_Werkstatt_an\" >Welche Kosten fallen f\u00fcr die Reparatur der Abgasanlage in der Werkstatt an?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/#Haftungsausschluss\" >Haftungsausschluss<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Welchen_Zweck_hat_die_Abgasuntersuchung_AU_beim_Auto\"><\/span>Welchen Zweck hat die Abgasuntersuchung (AU) beim Auto?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Die Abgasuntersuchung, kurz AU, ist vom Gesetzgeber <strong>f\u00fcr alle Kraftfahrzeuge vorgeschrieben<\/strong>. Fr\u00fcher wurde die AU als Abgassonderuntersuchung (ASU) bezeichnet. Hier gab es eine eigene Plakette und spezielle Regelungen f\u00fcr Autos ohne KAT und mit Vergaser. Heute ist die Abgasuntersuchung ein Bestandteil der T\u00dcV-Pr\u00fcfung und n\u00f6tig, damit das Fahrzeug seine Betriebserlaubnis beh\u00e4lt. Der offizielle Name lautet \u201eUntersuchung des Motormanagements und Abgasreinigungssystems\u201c, kurz UMA.<\/p>\n\n\n\n<p>Mit der AU wird bei allen Verbrennungsmotoren sichergestellt, dass diese nicht mehr Schadstoffe in der Umwelt verteilen als n\u00f6tig. Dazu werden alle Teile der Abgasanlage untersucht und anschlie\u00dfend der Schadstoffgehalt der Abgase gemessen. Der Pr\u00fcfer ermittelt den CO2-Aussto\u00df und den Gehalt an Stickoxiden, Kohlenmonoxid und Ru\u00dfpartikeln (<a href=\"\/shop\/motor-motoren\">nur bei einem Dieselmotor<\/a>) des Kraftfahrzeugs.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Wie wird die Abgasuntersuchung durchgef\u00fchrt?<\/h3>\n\n\n\n<p>Die Abgasuntersuchung stellt sicher, dass die vorgeschriebene Reinigung der Abgase von Schadstoffen noch gegeben ist. Der Pr\u00fcfer ermittelt durch Messung und Vergleich der Solldaten mit den Ist-Daten, ob das Auto noch den Vorgaben entspricht. Die Fahrzeuge werden bei der Herstellung in unterschiedliche Abgasnormen eingeteilt. Je nach Norm gelten unterschiedliche Grenzwerte und Vorgaben.<\/p>\n\n\n\n<p>Die aktuell geltenden Abgasnormen f\u00fcr Autos sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Euro 1 (seit Juli 1992)<\/li>\n\n\n\n<li>Euro 2 (seit Januar 1996)<\/li>\n\n\n\n<li>Euro 3 (seit Januar 2000)<\/li>\n\n\n\n<li>Euro 4 (seit Januar 2005)<\/li>\n\n\n\n<li>Euro 5 (seit September 2009)<\/li>\n\n\n\n<li>Euro 6 (seit September 2014)<\/li>\n\n\n\n<li>Euro 7 (Pflicht f\u00fcr neue Modelle ab 29. November 2026)<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Was kostet die Abgasuntersuchung?<\/h3>\n\n\n\n<p>Die Kosten f\u00fcr eine Abgasuntersuchung k\u00f6nnen sich bei den einzelnen Organisationen wie T\u00dcV, DEKRA, K\u00dcS oder GT\u00dc leicht unterscheiden. Die Unterschiede betragen je nach Organisation und Region bis zu zehn Prozent. Die Kosten belaufen sich auf:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>AU f\u00fcr PKW circa 30 \u20ac<\/li>\n\n\n\n<li>AU f\u00fcr Motorrad 40 \u20ac<\/li>\n\n\n\n<li>HU\/AU in Kombination f\u00fcr PKW zwischen 150 und 165 \u20ac<\/li>\n\n\n\n<li>HU\/AU in Kombination f\u00fcr Motorrad zwischen 75 und 95 \u20ac<\/li>\n<\/ul>\n\n\n\n<p class=\"has-small-font-size\">Stand 09.2023<\/p>\n\n\n\n<p>Abweichende Preise gelten, wenn Sie den <strong>Pr\u00fcfungstermin um mehr als zwei Monate verpasst<\/strong> haben. In diesem Fall f\u00e4llt f\u00fcr die HU und AU eine h\u00f6here Geb\u00fchr an und im Fall der AU wird sogar eine zus\u00e4tzliche \u00dcberpr\u00fcfung durchgef\u00fchrt. Dies nennt sich <strong>vertiefte Hauptuntersuchung<\/strong>. Auch hier kann es zwischen den einzelnen Organisationen kleine Preisunterschiede geben.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Welche Kraftfahrzeuge m\u00fcssen zur Abgasuntersuchung?<\/h3>\n\n\n\n<p>Grunds\u00e4tzlich m\u00fcssen alle Autos unabh\u00e4ngig vom Fahrzeughersteller zur Abgasuntersuchung. Als Fristen gelten dabei, dass Neuwagen erstmals nach drei Jahren und Gebrauchtwagen alle zwei Jahre zur Haupt- und Abgasuntersuchung m\u00fcssen.<\/p>\n\n\n\n<p>Es gibt allerdings Ausnahmen, die beispielsweise f\u00fcr Oldtimer gelten. Folgende Fahrzeugkategorien ben\u00f6tigen keine Abgasuntersuchung:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Benzinmotor Zulassung vor 01. Juli 1969<\/li>\n\n\n\n<li>Dieselmotor Zulassung vor 01. Januar 1977<\/li>\n\n\n\n<li>Autos und Motorr\u00e4der mit Kurzzeitkennzeichen<\/li>\n\n\n\n<li>Arbeitsmaschinen bis 20 km\/h<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wie_laeuft_eine_Abgasuntersuchung_beim_Auto_ab\"><\/span>Wie l\u00e4uft eine Abgasuntersuchung beim Auto ab?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Der Aufbau der AU beim PKW ist immer gleich:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Zuerst nimmt der Pr\u00fcfer die Fahrzeugdaten auf. Dazu geh\u00f6ren die Fabrikatnummer, Erstzulassung und der Kilometerstand.<\/li>\n\n\n\n<li>Nun erfolgt eine <strong>Sichtpr\u00fcfung <\/strong>der f\u00fcr die Abgasanlage relevanten Teile. Dazu geh\u00f6ren Auspuffanlage, <a href=\"\/shop\/abgasanlage-katalysator\">speziell der Katalysator<\/a> und der <a href=\"\/shop\/abgasanlage-russpartikelfilter\">Ru\u00dfpartikelfilter bei Dieselmotoren<\/a>. Gepr\u00fcft wird auf Sch\u00e4den, Korrosion oder Ver\u00e4nderungen, etwa durch Tuning.<\/li>\n\n\n\n<li>Dann erfolgt eine <strong>Messung <\/strong>des Schadstoffaussto\u00dfes mit einer Messsonde im Auspuff im Leerlauf und bei vorgeschriebenen Drehzahlen.<\/li>\n\n\n\n<li>Die ermittelten Messwerte werden mit den Richtwerten verglichen.<\/li>\n\n\n\n<li>Bei Bestehen wird eine Bescheinigung ausgestellt. Bei Nichtbestehen kann der Besitzer des Autos eine Nachpr\u00fcfung innerhalb eines Monats durchf\u00fchren lassen.<\/li>\n<\/ul>\n\n\n\n<p>Vor dem <a href=\"https:\/\/www.autoteile-markt.de\/blog\/abgasskandal-seit-wann-weiss-vw-von-schummelsoftware\/\">Abgasskandal (Dieselgate) im Kreise gro\u00dfer Automobilkonzerne<\/a> erfolgte die AU bei neueren Autos als reine Onboard-Diagnose durch Auslesen der Motorwerte des KFZ. Nach dem Abgasskandal wurde die Gesetzgebung ge\u00e4ndert, sodass nun alle Autos mit Auspuffmessung zu pr\u00fcfen sind.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Kann ich eine Hauptuntersuchung ohne Abgasuntersuchung durchf\u00fchren?<\/h3>\n\n\n\n<p>Seit 2010 ist die AU ein Bestandteil der HU. Die meisten Werkst\u00e4tten und Pr\u00fcfstellen bieten daher grunds\u00e4tzlich die HU\/AU als Kombination an. Es m\u00fcssen jedoch nicht beide Pr\u00fcfungen zur gleichen Zeit durchgef\u00fchrt werden. Der Zeitraum zwischen den Pr\u00fcfungen darf allerdings einen Monat nicht \u00fcberschreiten.<\/p>\n\n\n\n<p>Wenn es sich f\u00fcr Sie aus organisatorischen Gr\u00fcnden anbietet, k\u00f6nnen Sie die Abgasuntersuchung des Autos separat in einer Werkstatt durchf\u00fchren lassen. Wichtig ist aber in diesem Fall, dass Sie die Bescheinigung der zuerst durchgef\u00fchrten Pr\u00fcfung zur zweiten mitbringen. Nur, wenn beide Pr\u00fcfungen nachgewiesen werden, erh\u00e4lt das Auto die neue Plakette.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Welche Strafe droht, wenn der Termin zur Abgasuntersuchung \u00fcberzogen wird?<\/h3>\n\n\n\n<p>Wenn Sie die Abgasuntersuchung nicht im angedachten Zeitraum durchf\u00fchren, fallen Strafen an. Diese beginnen bei kleinen Bu\u00dfgeldern und steigen, wenn der Zeitraum besonders lang verpasst wird. Das Bu\u00dfgeld gilt f\u00fcr die verpasste Hauptuntersuchung, da beide Pr\u00fcfungen beim Auto eine Einheit bilden.<\/p>\n\n\n\n<p>Die Strafen f\u00fcr das Vers\u00e4umen der Hauptuntersuchung und Abgasuntersuchung sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Termin um <strong>zwei bis vier Monate<\/strong> \u00fcberzogen: 15 \u20ac Bu\u00dfgeld<\/li>\n\n\n\n<li>Frist um <strong>vier bis acht Monate<\/strong> \u00fcberzogen: 25 \u20ac Bu\u00dfgeld<\/li>\n\n\n\n<li>Termin um <strong>mehr als acht Monate<\/strong> \u00fcberzogen: 60 \u20ac Bu\u00dfgeld und ein Punkt in Flensburg<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Kann ich eine Abgasuntersuchung beim Auto selber durchf\u00fchren?<\/h3>\n\n\n\n<p>Nein, das ist nicht m\u00f6glich. Die Abgasuntersuchung muss von einer zugelassenen Werkstatt durchgef\u00fchrt werden. Sie k\u00f6nnen allerdings im Voraus selbst die wichtigsten Punkte kontrollieren. Mit ein wenig Werkzeug und Geschick k\u00f6nnen Sie auch Undichtigkeiten beseitigen, \u00d6lverlust stoppen und andere kleine Reparaturen vornehmen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Vorbereitung_zur_AU_%E2%80%93_Schritt_fuer_Schritt_Anleitung\"><\/span>Vorbereitung zur AU \u2013 Schritt f\u00fcr Schritt Anleitung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Ihr Auto zeigt Symptome wie Ru\u00df oder Rauch aus dem Auspuff? Eine deutliche Entwicklung von Qualm oder ein erh\u00f6hter \u00d6lverbrauch sind h\u00e4ufig Anzeichen daf\u00fcr, dass ein Defekt die Verbrennung st\u00f6rt. Damit stimmen auch die Abgaswerte nicht und das Auto w\u00fcrde die AU nicht bestehen.<\/p>\n\n\n\n<p>Wenn absehbar ist, dass das Auto bei der Abgasuntersuchung durchf\u00e4llt, sollten Sie die Sch\u00e4den im Voraus beseitigen. Somit sparen Sie sich die Kosten und den Zeitaufwand f\u00fcr die Nachpr\u00fcfung. Viele Arbeiten k\u00f6nnen Sie selber erledigen und kaputte Teile wechseln.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Sichtpr\u00fcfung<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-medium\"><a href=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Bild-3-Sichtkontrole-Abgasanlage-Auto.jpg\"><img  title=\"Abgasuntersuchung beim Auto \u2013 Was Sie vor der Pr\u00fcfung wissen sollten!\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Bild-3-Sichtkontrole-Abgasanlage-Auto-300x199.jpg\"  alt=\"Bild-3-Sichtkontrole-Abgasanlage-Auto-300x199 Abgasuntersuchung beim Auto \u2013 Was Sie vor der Pr\u00fcfung wissen sollten!\"  class=\"wp-image-10646\" srcset=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Bild-3-Sichtkontrole-Abgasanlage-Auto-300x199.jpg 300w, https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Bild-3-Sichtkontrole-Abgasanlage-Auto.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption class=\"wp-element-caption\">\u00a9Foto: runzelkorn\/depositphotos.com<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Der erste Check f\u00fchrt zum <a href=\"\/shop\/innenausstattung-armaturenbrett\">Armaturenbrett des Autos<\/a>. Schalten Sie die Z\u00fcndung ein und werfen Sie einen Blick auf die Kontrollleuchten. Beim Einschalten sollten alle kurz aufleuchten und innerhalb der n\u00e4chsten Sekunden erl\u00f6schen. Wenn beispielsweise die Motorkontrollleuchte weiterleuchtet oder beim Motorstart anspringt, ist das ein Hinweis auf einen Fehler an der Abgasanlage.<\/p>\n\n\n\n<p>Unterziehen Sie nun alle Teile einer <strong>Sichtpr\u00fcfung auf Korrosion oder Besch\u00e4digungen<\/strong>. Zu den relevanten Teilen geh\u00f6ren insbesondere:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Katalysator<\/li>\n\n\n\n<li>Ru\u00dfpartikelfilter<\/li>\n\n\n\n<li>Auspuffanlage, <a href=\"\/shop\/abgasanlage-abgaskruemmer\">also der Abgaskr\u00fcmmer<\/a>, Vorschalld\u00e4mpfer, Mittelschalld\u00e4mpfer <a href=\"\/shop\/abgasanlage-endschalldaempfer\">und der Endschalld\u00e4mpfer<\/a><\/li>\n\n\n\n<li><a href=\"\/shop\/abgasanlage-lambdasonde\">Lambdasonden bzw. Abgassonden<\/a><\/li>\n\n\n\n<li><a href=\"\/shop\/abgasanlage-auspuffrohr\">Abgasrohr<\/a><\/li>\n<\/ul>\n\n\n\n<p>Besch\u00e4digte Teile sollten Sie vor der Pr\u00fcfung wechseln, da diese mit hoher Wahrscheinlichkeit bei der HU oder AU durchfallen. Wenn alle Teile augenscheinlich in Ordnung sind, fahren Sie fort.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Wenn Ger\u00e4te vorhanden: Diagnose des Motors<\/h3>\n\n\n\n<p>Wenn Sie die M\u00f6glichkeit haben, nutzen Sie die das Onboard-Diagnosesystem (OBD) des Autos. Hierf\u00fcr gibt es viele verschiedene Ger\u00e4te in unterschiedlichen Preisklassen. Das Ger\u00e4t wird einfach an eine spezielle Steckdose angesteckt und greift von dort auf das Motorsteuerger\u00e4t zu.<\/p>\n\n\n\n<p>\u00dcber die OBD-Dose finden Sie Meldungen \u00fcber Fehlfunktionen im Motor in Form von Fehlercodes. Diese Fehlercodes werden beispielsweise bei falschen Temperaturen oder schlechten Lambdawerten erzeugt. Sie geben gute Hinweise darauf, wenn Fehler vorliegen. Oftmals k\u00f6nnen Sie anhand der Fehlercodes sogar genau ermitteln, welches Teil den Fehler misst beziehungsweise verursacht.<\/p>\n\n\n\n<p>Falls Sie Zugriff auf eine vollst\u00e4ndig ausger\u00fcstete Werkstatt haben, k\u00f6nnen Sie auch die Messung per Sonde durchf\u00fchren. Dann wissen Sie sicher, ob das Fahrzeug die Pr\u00fcfung besteht. Die Sollwerte des Fahrzeugs finden Sie entweder im Handbuch oder Internet.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Eingrenzung eventueller Fehler<\/h3>\n\n\n\n<p>Wenn Sie nach der Pr\u00fcfung auf Sicht und dem Auslesen der Fehler keine Defekte entdeckt haben, k\u00f6nnen noch andere Teile Fehler verursachen. Einige davon k\u00f6nnen Sie bei einer detaillierten Pr\u00fcfung des Motors ausfindig machen oder kurzerhand ausbauen, andere nur anhand der Symptome erkennen.<\/p>\n\n\n\n<p>M\u00f6gliche Quellen falscher Abgaswerte rund um den Motor sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00d6lstand zu niedrig<\/li>\n\n\n\n<li>verschlissene Dichtungen<\/li>\n\n\n\n<li>undichte Verbindungen oder Verschraubungen<\/li>\n\n\n\n<li>Z\u00fcndanlage, speziell <a href=\"\/shop\/zuend-gluehanlage-zuendkerzen\">Z\u00fcndkerzen beim Benzinmotor<\/a> oder <a href=\"\/shop\/zuend-gluehanlage-gluehkerze\">Gl\u00fchkerzen beim Dieselmotor<\/a> verschlissen<\/li>\n\n\n\n<li>Fehler an der Harnstoffeinspritzung<\/li>\n\n\n\n<li>Verschlei\u00df der Abgasr\u00fcckf\u00fchrung, z. B. <a href=\"\/shop\/abgasanlage-agr-ventil\">AGR-Ventil fest oder verstopft<\/a><\/li>\n\n\n\n<li><a href=\"\/shop\/abgasanlage-turbolader\">Turbolader defekt<\/a><\/li>\n\n\n\n<li>Abgasreinigung fehlerhaft, z. B. Lambdasonde kaputt<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">4. Defekte Teile wechseln beziehungsweise Fehler beheben<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-medium\"><a href=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Bild-2-Rost-Auspuff-Schalldaempfer.jpg\"><img  title=\"Abgasuntersuchung beim Auto \u2013 Was Sie vor der Pr\u00fcfung wissen sollten!\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Bild-2-Rost-Auspuff-Schalldaempfer-300x225.jpg\"  alt=\"Bild-2-Rost-Auspuff-Schalldaempfer-300x225 Abgasuntersuchung beim Auto \u2013 Was Sie vor der Pr\u00fcfung wissen sollten!\"  class=\"wp-image-10647\" srcset=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Bild-2-Rost-Auspuff-Schalldaempfer-300x225.jpg 300w, https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Bild-2-Rost-Auspuff-Schalldaempfer.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption class=\"wp-element-caption\">\u00a9Foto: KanoonPhoto\/depositphotos.com<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Wenn Sie nun eines oder mehrere kaputte Teile ausfindig gemacht haben, m\u00fcssen Sie den Schaden reparieren. Auch hier k\u00f6nnen Sie viele Arbeiten selber erledigen, sofern Sie \u00fcber das entsprechende Werkzeug verf\u00fcgen. Zu diesen T\u00e4tigkeiten geh\u00f6ren:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00d6lwechsel durchf\u00fchren<\/li>\n\n\n\n<li>Additiv auff\u00fcllen (AdBlue)<\/li>\n\n\n\n<li>Dichtungen erneuern<\/li>\n\n\n\n<li><a href=\"\/shop\/filter-luftfilter\">Luftfilter f\u00fcr die Ansaugluft<\/a> wechseln<\/li>\n\n\n\n<li>K\u00fchlwasser auff\u00fcllen oder tauschen<\/li>\n\n\n\n<li>Lambdasonde erneuern<\/li>\n\n\n\n<li>Endschalld\u00e4mpfer ersetzen<\/li>\n\n\n\n<li>Austausch von Katalysator oder Ru\u00dfpartikelfilter<\/li>\n<\/ul>\n\n\n\n<p>Es f\u00fchren allerdings nicht nur Sch\u00e4den, sondern auch Ver\u00e4nderungen am Auto zum Nichtbestehen der Pr\u00fcfung. Das k\u00f6nnte zum Beispiel ein nicht zugelassener Sportluftfilter oder Sportendtopf sein. Derartige Bauteile machen das Fahrzeug nicht nur unverh\u00e4ltnism\u00e4\u00dfig laut, sondern k\u00f6nnen auch bei der HU oder AU zum Hindernis werden. Achten Sie daher beim Kauf immer darauf, dass Ersatzteile f\u00fcr den Einsatz im Stra\u00dfenverkehr zugelassen sind.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5. Funktion pr\u00fcfen<\/h3>\n\n\n\n<p>Nach dem Wechseln der kaputten Teile sollten Sie nach M\u00f6glichkeit noch einmal \u00fcberpr\u00fcfen, ob das Problem behoben ist. Machen Sie eine Probefahrt und lesen Sie den Fehlerspeicher erneut aus. Wenn vorhanden, f\u00fchren Sie auch die Messung mit der Sonde erneut durch. Wenn alles in Ordnung ist, dann ist das Auto fit f\u00fcr die Abgasuntersuchung bei der Werkstatt oder Pr\u00fcfstelle.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">6. Geheimtipps: \u201eFreiblasen\u201c und Motor auf Betriebstemperatur bringen<\/h3>\n\n\n\n<p>Bei einem Fahrzeug am Grenzwert kann es helfen, dieses ein gutes St\u00fcck auf der Autobahn zu fahren. Der Grund: Bei der Fahrt mit h\u00f6herer Geschwindigkeit und Drehzahl herrschen optimale Bedingungen, um die Auspuffanlage zu reinigen, also sozusagen \u201efreizubrennen\u201c. Unternehmen Sie diese Fahrt wenn m\u00f6glich kurz vor der Pr\u00fcfung, beispielsweise als Ausflug am Wochenende vorher. Auch eine Fahrt mit teurem Kraftstoff wie \u201eAral Ultimate\u201c kann bei der Reinigung helfen.<\/p>\n\n\n\n<p>Das Abgassystem des Motors ist auf dessen normale Betriebstemperatur ausgelegt. Sollten Sie nur eine kurze Strecke zur Pr\u00fcfstelle zu fahren haben, nehmen Sie einen kleinen Umweg, damit der Motor auf Betriebstemperatur kommt. Das sorgt daf\u00fcr, dass das System optimal arbeitet. So haben Sie eine h\u00f6here Chance, dass die Werte innerhalb der geforderten Grenzen liegen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Welche_Kosten_fallen_fuer_die_Reparatur_der_Abgasanlage_in_der_Werkstatt_an\"><\/span>Welche Kosten fallen f\u00fcr die Reparatur der Abgasanlage in der Werkstatt an?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Reparaturen am Auto im Bereich der Abgasanlage sind sehr unterschiedlich teuer. Je nach Aufwand und Verschlei\u00df- oder Ersatzteil liegen die Kosten zwischen dem zweistelligen und vierstelligen Bereich. Ein paar Beispiele f\u00fcr Reparaturen sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Luftfilter tauschen: 50 bis 100 \u20ac<\/li>\n\n\n\n<li>\u00d6lwechsel: 50 bis 150 \u20ac<\/li>\n\n\n\n<li>Lambdasonde wechseln: 150 bis 300 \u20ac<\/li>\n\n\n\n<li>Endschalld\u00e4mpfer erneuen: 200 bis 500 \u20ac<\/li>\n\n\n\n<li>Katalysator tauschen: 500 bis 1500 \u20ac<\/li>\n\n\n\n<li>Ru\u00dfpartikelfilter wechseln: 1000 bis 2000 \u20ac<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">AU relevante Teile selber wechseln und Geld sparen<\/h3>\n\n\n\n<p>Oftmals sind die Teile der Abgasanlage am Auto sehr teuer. Sie k\u00f6nnen hier \u00fcber die H\u00e4lfte der Kosten sparen, indem Sie verschlissene Teile selber tauschen. In unseren Blogbeitr\u00e4gen finden Sie Einbauanleitungen f\u00fcr viele typische Auto Ersatzteile.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Haftungsausschluss\"><\/span>Haftungsausschluss<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Unsere Ratgeber enthalten viele fachliche Informationen rund um das KFZ, die wir sorgf\u00e4ltig zusammengetragen haben. Diese Artikel k\u00f6nnen allerdings die Fachkenntnis eines Spezialisten nicht ersetzen. Autoteile-Markt haftet daher nicht f\u00fcr Sch\u00e4den und Verletzungen, die durch unsachgem\u00e4\u00df ausgef\u00fchrte Reparaturen entstehen. Wir empfehlen grunds\u00e4tzlich, Arbeiten am KFZ nur von einem Fachmann ausf\u00fchren zu lassen.<\/p>\n\n\n<style>#sp-ea-18663 .spcollapsing { height: 0; overflow: hidden; transition-property: height;transition-duration: 300ms;}.sp-easy-accordion-enabled .eap_section_title_18663, body .eap_section_title_18663 { color: #444; margin-bottom:  30px; }#sp-ea-18663.sp-easy-accordion>.sp-ea-single {margin-bottom: 10px; border: 1px solid #e2e2e2; }#sp-ea-18663.sp-easy-accordion>.sp-ea-single>.ea-header a {color: #444;}#sp-ea-18663.sp-easy-accordion>.sp-ea-single>.sp-collapse>.ea-body {background: #fff; color: #444;}#sp-ea-18663.sp-easy-accordion>.sp-ea-single {background: #eee;}#sp-ea-18663.sp-easy-accordion>.sp-ea-single>.ea-header a .ea-expand-icon { float: left; color: #444;font-size: 16px;}<\/style><h2 class=\"eap_section_title eap_section_title_18663\">FAQ \u2013 Abgasuntersuchung (AU)<\/h2><div id=\"sp_easy_accordion-1757149783\"><div id=\"sp-ea-18663\" class=\"sp-ea-one sp-easy-accordion\" data-ea-active=\"ea-click\" data-ea-mode=\"vertical\" data-preloader=\"\" data-scroll-active-item=\"\" data-offset-to-scroll=\"0\"><div class=\"ea-card ea-expand sp-ea-single\"><h3 class=\"ea-header\"><a class=\"collapsed\" id=\"ea-header-186630\" role=\"button\" data-sptoggle=\"spcollapse\" data-sptarget=\"#collapse186630\" aria-controls=\"collapse186630\" href=\"#\" aria-expanded=\"true\" tabindex=\"0\"><i aria-hidden=\"true\" role=\"presentation\" class=\"ea-expand-icon eap-icon-ea-expand-minus\"><\/i> Was ist die Abgasuntersuchung?<\/a><\/h3><div class=\"sp-collapse spcollapse collapsed show\" id=\"collapse186630\" data-parent=\"#sp-ea-18663\" role=\"region\" aria-labelledby=\"ea-header-186630\"> <div class=\"ea-body\"><p>Die Abgasuntersuchung, kurz AU, stellt sicher, dass Kraftfahrzeuge nur so viel Schadstoffe aussto\u00dfen wie unbedingt n\u00f6tig. Sie tr\u00e4gt damit ma\u00dfgeblich zu einer Reduzierung der Luftverschmutzung durch Kfz bei. Die AU ist ein Bestandteil der Hauptuntersuchung (HU) und wird ben\u00f6tigt, damit das Fahrzeug eine neue Plakette erh\u00e4lt. Die Frist betr\u00e4gt wie bei der HU zwei Jahre.<\/p><\/div><\/div><\/div><div class=\"ea-card sp-ea-single\"><h3 class=\"ea-header\"><a class=\"collapsed\" id=\"ea-header-186631\" role=\"button\" data-sptoggle=\"spcollapse\" data-sptarget=\"#collapse186631\" aria-controls=\"collapse186631\" href=\"#\" aria-expanded=\"false\" tabindex=\"0\"><i aria-hidden=\"true\" role=\"presentation\" class=\"ea-expand-icon eap-icon-ea-expand-plus\"><\/i> Wo und wie wird die AU durchgef\u00fchrt?<\/a><\/h3><div class=\"sp-collapse spcollapse \" id=\"collapse186631\" data-parent=\"#sp-ea-18663\" role=\"region\" aria-labelledby=\"ea-header-186631\"> <div class=\"ea-body\"><p>Die Durchf\u00fchrung \u00fcbernehmen anerkannte Pr\u00fcforganisationen wie T\u00fcv, Dekra, K\u00dcS und GT\u00dc. Eine Abgasuntersuchung besteht bei den meisten Fahrzeugen aus zwei Schritten:<\/p><ol><li>Auslesen der Motorsteuerung und Pr\u00fcfung auf Fehlermeldungen<\/li><li>Messung des Abgasstroms am Auspuffrohr<\/li><\/ol><\/div><\/div><\/div><div class=\"ea-card sp-ea-single\"><h3 class=\"ea-header\"><a class=\"collapsed\" id=\"ea-header-186632\" role=\"button\" data-sptoggle=\"spcollapse\" data-sptarget=\"#collapse186632\" aria-controls=\"collapse186632\" href=\"#\" aria-expanded=\"false\" tabindex=\"0\"><i aria-hidden=\"true\" role=\"presentation\" class=\"ea-expand-icon eap-icon-ea-expand-plus\"><\/i> Kann ich die Chancen meines Autos auf eine erfolgreiche AU verbessern?<\/a><\/h3><div class=\"sp-collapse spcollapse \" id=\"collapse186632\" data-parent=\"#sp-ea-18663\" role=\"region\" aria-labelledby=\"ea-header-186632\"> <div class=\"ea-body\"><p>Ja, Sie k\u00f6nnen Ma\u00dfnahmen ergreifen, um das Auto optimal auf die Abgasuntersuchung vorzubereiten. Die M\u00f6glichkeiten sind:<\/p><ul><li>Eine Tankf\u00fcllung vor der Pr\u00fcfung mit Super Plus oder 100-Oktan fahren, dies kann Ablagerungen reduzieren.<\/li><li>Kurz vor der Abgasuntersuchung eine l\u00e4ngere Autobahnfahrt unternehmen, um den Abgastrakt zu reinigen.<\/li><li>Das Auto direkt vor der Pr\u00fcfung auf Betriebstemperatur bringen, da bei dieser Temperatur der Aussto\u00df am geringsten ist.<\/li><\/ul><\/div><\/div><\/div><div class=\"ea-card sp-ea-single\"><h3 class=\"ea-header\"><a class=\"collapsed\" id=\"ea-header-186633\" role=\"button\" data-sptoggle=\"spcollapse\" data-sptarget=\"#collapse186633\" aria-controls=\"collapse186633\" href=\"#\" aria-expanded=\"false\" tabindex=\"0\"><i aria-hidden=\"true\" role=\"presentation\" class=\"ea-expand-icon eap-icon-ea-expand-plus\"><\/i> Was passiert, wenn ich die Frist f\u00fcr meine AU verpasse?<\/a><\/h3><div class=\"sp-collapse spcollapse \" id=\"collapse186633\" data-parent=\"#sp-ea-18663\" role=\"region\" aria-labelledby=\"ea-header-186633\"> <div class=\"ea-body\"><p>Ohne erfolgreiche Abgasuntersuchung und Hauptuntersuchung erh\u00e4lt das Auto keine Pr\u00fcfplakette. Die f\u00fchrt zu einem Bu\u00dfgeld und im Extremfall zu Punkten im VZR. Au\u00dferdem f\u00e4llt bei \u00dcberschreitung des Termins um mehr als zwei Monate eine \u201evertiefte Hauptuntersuchung\u201c an. Diese ist mit einer genaueren Pr\u00fcfung und erh\u00f6hten Kosten verbunden.<\/p><\/div><\/div><\/div><div class=\"ea-card sp-ea-single\"><h3 class=\"ea-header\"><a class=\"collapsed\" id=\"ea-header-186634\" role=\"button\" data-sptoggle=\"spcollapse\" data-sptarget=\"#collapse186634\" aria-controls=\"collapse186634\" href=\"#\" aria-expanded=\"false\" tabindex=\"0\"><i aria-hidden=\"true\" role=\"presentation\" class=\"ea-expand-icon eap-icon-ea-expand-plus\"><\/i> Was mache ich, wenn mein Auto die AU nicht besteht?<\/a><\/h3><div class=\"sp-collapse spcollapse \" id=\"collapse186634\" data-parent=\"#sp-ea-18663\" role=\"region\" aria-labelledby=\"ea-header-186634\"> <div class=\"ea-body\"><p>Bei Nichtbestehen der Pr\u00fcfung erhalten Sie ein Pr\u00fcfprotokoll mit den gemessenen Werten. Eine Werkstatt kann anhand der Messwerte und der Onboard-Diagnose ermitteln, wo der Fehler liegt. Nach der Reparatur k\u00f6nnen Sie das Fahrzeug innerhalb eines Monats gegen eine geringe Geb\u00fchr zur Nachpr\u00fcfung vorstellen.<\/p><\/div><\/div><\/div><script type=\"application\/ld+json\">{ \"@context\": \"https:\/\/schema.org\", \"@type\": \"FAQPage\", \"@id\": \"sp-ea-schema-18663-6a04aa15e6434\", \"mainEntity\": [{ \"@type\": \"Question\", \"name\": \"Was ist die Abgasuntersuchung?\", \"acceptedAnswer\": { \"@type\": \"Answer\", \"text\": \"Die Abgasuntersuchung, kurz AU, stellt sicher, dass Kraftfahrzeuge nur so viel Schadstoffe aussto\u00dfen wie unbedingt n\u00f6tig. Sie tr\u00e4gt damit ma\u00dfgeblich zu einer Reduzierung der Luftverschmutzung durch Kfz bei. Die AU ist ein Bestandteil der Hauptuntersuchung (HU) und wird ben\u00f6tigt, damit das Fahrzeug eine neue Plakette erh\u00e4lt. Die Frist betr\u00e4gt wie bei der HU zwei Jahre.\" } },{ \"@type\": \"Question\", \"name\": \"Wo und wie wird die AU durchgef\u00fchrt?\", \"acceptedAnswer\": { \"@type\": \"Answer\", \"text\": \"Die Durchf\u00fchrung \u00fcbernehmen anerkannte Pr\u00fcforganisationen wie T\u00fcv, Dekra, K\u00dcS und GT\u00dc. Eine Abgasuntersuchung besteht bei den meisten Fahrzeugen aus zwei Schritten:<ol><li>Auslesen der Motorsteuerung und Pr\u00fcfung auf Fehlermeldungen<\/li><li>Messung des Abgasstroms am Auspuffrohr<\/li><\/ol>\" } },{ \"@type\": \"Question\", \"name\": \"Kann ich die Chancen meines Autos auf eine erfolgreiche AU verbessern?\", \"acceptedAnswer\": { \"@type\": \"Answer\", \"text\": \"Ja, Sie k\u00f6nnen Ma\u00dfnahmen ergreifen, um das Auto optimal auf die Abgasuntersuchung vorzubereiten. Die M\u00f6glichkeiten sind:<ul><li>Eine Tankf\u00fcllung vor der Pr\u00fcfung mit Super Plus oder 100-Oktan fahren, dies kann Ablagerungen reduzieren.<\/li><li>Kurz vor der Abgasuntersuchung eine l\u00e4ngere Autobahnfahrt unternehmen, um den Abgastrakt zu reinigen.<\/li><li>Das Auto direkt vor der Pr\u00fcfung auf Betriebstemperatur bringen, da bei dieser Temperatur der Aussto\u00df am geringsten ist.<\/li><\/ul>\" } },{ \"@type\": \"Question\", \"name\": \"Was passiert, wenn ich die Frist f\u00fcr meine AU verpasse?\", \"acceptedAnswer\": { \"@type\": \"Answer\", \"text\": \"Ohne erfolgreiche Abgasuntersuchung und Hauptuntersuchung erh\u00e4lt das Auto keine Pr\u00fcfplakette. Die f\u00fchrt zu einem Bu\u00dfgeld und im Extremfall zu Punkten im VZR. Au\u00dferdem f\u00e4llt bei \u00dcberschreitung des Termins um mehr als zwei Monate eine \u201evertiefte Hauptuntersuchung\u201c an. Diese ist mit einer genaueren Pr\u00fcfung und erh\u00f6hten Kosten verbunden.\" } },{ \"@type\": \"Question\", \"name\": \"Was mache ich, wenn mein Auto die AU nicht besteht?\", \"acceptedAnswer\": { \"@type\": \"Answer\", \"text\": \"Bei Nichtbestehen der Pr\u00fcfung erhalten Sie ein Pr\u00fcfprotokoll mit den gemessenen Werten. Eine Werkstatt kann anhand der Messwerte und der Onboard-Diagnose ermitteln, wo der Fehler liegt. Nach der Reparatur k\u00f6nnen Sie das Fahrzeug innerhalb eines Monats gegen eine geringe Geb\u00fchr zur Nachpr\u00fcfung vorstellen.\" } }] }<\/script><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"Die Abgasuntersuchung beim Auto dient dazu, den Schadstoffgehalt der Abgase zu pr\u00fcfen. Diese m\u00fcssen innerhalb gesetzlicher Grenzwerte liegen. Das ist wichtig, damit besonders \u00e4ltere Fahrzeuge nicht zur sprichw\u00f6rtlichen \u201eDreckschleuder\u201c werden.\n... <br \/><a class=\"read-more\" href=\"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/\">Weiterlesen<\/a>","protected":false},"author":6,"featured_media":10645,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-10644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ratgeber"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abgasuntersuchung beim Auto \u2013 Was Sie vor der Pr\u00fcfung wissen sollten!<\/title>\n<meta name=\"description\" content=\"\u00a9Foto: weyo\/depositphotos.com Die Abgasuntersuchung beim Auto dient dazu, den Schadstoffgehalt der Abgase zu pr\u00fcfen. Diese m\u00fcssen innerhalb gesetzlicher\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abgasuntersuchung beim Auto \u2013 Was Sie vor der Pr\u00fcfung wissen sollten!\" \/>\n<meta property=\"og:description\" content=\"\u00a9Foto: weyo\/depositphotos.com Die Abgasuntersuchung beim Auto dient dazu, den Schadstoffgehalt der Abgase zu pr\u00fcfen. Diese m\u00fcssen innerhalb gesetzlicher\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/\" \/>\n<meta property=\"og:site_name\" content=\"Autoteile-Markt.de Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AutoteileMarktde\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-06T09:43:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-06T09:43:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Titelbild-Abgasuntersuchung-AU.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"F. Selleng\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@autoteilemarkt\" \/>\n<meta name=\"twitter:site\" content=\"@autoteilemarkt\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"F. Selleng\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abgasuntersuchung beim Auto \u2013 Was Sie vor der Pr\u00fcfung wissen sollten!","description":"\u00a9Foto: weyo\/depositphotos.com Die Abgasuntersuchung beim Auto dient dazu, den Schadstoffgehalt der Abgase zu pr\u00fcfen. Diese m\u00fcssen innerhalb gesetzlicher","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/","og_locale":"de_DE","og_type":"article","og_title":"Abgasuntersuchung beim Auto \u2013 Was Sie vor der Pr\u00fcfung wissen sollten!","og_description":"\u00a9Foto: weyo\/depositphotos.com Die Abgasuntersuchung beim Auto dient dazu, den Schadstoffgehalt der Abgase zu pr\u00fcfen. Diese m\u00fcssen innerhalb gesetzlicher","og_url":"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/","og_site_name":"Autoteile-Markt.de Blog","article_publisher":"https:\/\/www.facebook.com\/AutoteileMarktde\/","article_published_time":"2025-09-06T09:43:23+00:00","article_modified_time":"2025-09-06T09:43:24+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Titelbild-Abgasuntersuchung-AU.jpg","type":"image\/jpeg"}],"author":"F. Selleng","twitter_card":"summary_large_image","twitter_creator":"@autoteilemarkt","twitter_site":"@autoteilemarkt","twitter_misc":{"Written by":"F. Selleng","Est. reading time":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/#article","isPartOf":{"@id":"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/"},"author":{"name":"F. Selleng","@id":"https:\/\/www.autoteile-markt.de\/blog\/#\/schema\/person\/cea0595ff01d1a3de7b2f838d87645cd"},"headline":"Abgasuntersuchung beim Auto \u2013 Was Sie vor der Pr\u00fcfung wissen sollten!","datePublished":"2025-09-06T09:43:23+00:00","dateModified":"2025-09-06T09:43:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/"},"wordCount":1972,"image":{"@id":"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Titelbild-Abgasuntersuchung-AU.jpg","articleSection":["Ratgeber"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/","url":"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/","name":"Abgasuntersuchung beim Auto \u2013 Was Sie vor der Pr\u00fcfung wissen sollten!","isPartOf":{"@id":"https:\/\/www.autoteile-markt.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/#primaryimage"},"image":{"@id":"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Titelbild-Abgasuntersuchung-AU.jpg","datePublished":"2025-09-06T09:43:23+00:00","dateModified":"2025-09-06T09:43:24+00:00","author":{"@id":"https:\/\/www.autoteile-markt.de\/blog\/#\/schema\/person\/cea0595ff01d1a3de7b2f838d87645cd"},"description":"\u00a9Foto: weyo\/depositphotos.com Die Abgasuntersuchung beim Auto dient dazu, den Schadstoffgehalt der Abgase zu pr\u00fcfen. Diese m\u00fcssen innerhalb gesetzlicher","breadcrumb":{"@id":"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/#primaryimage","url":"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Titelbild-Abgasuntersuchung-AU.jpg","contentUrl":"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2023\/09\/Titelbild-Abgasuntersuchung-AU.jpg","width":1000,"height":667,"caption":"\u00a9Foto: weyo\/depositphotos.com"},{"@type":"BreadcrumbList","@id":"https:\/\/www.autoteile-markt.de\/blog\/abgasuntersuchung-beim-auto-was-sie-vor-der-pruefung-wissen-sollten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.autoteile-markt.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Abgasuntersuchung beim Auto \u2013 Was Sie vor der Pr\u00fcfung wissen sollten!"}]},{"@type":"WebSite","@id":"https:\/\/www.autoteile-markt.de\/blog\/#website","url":"https:\/\/www.autoteile-markt.de\/blog\/","name":"Autoteile-Markt.de Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.autoteile-markt.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.autoteile-markt.de\/blog\/#\/schema\/person\/cea0595ff01d1a3de7b2f838d87645cd","name":"F. Selleng","description":"F. Selleng wurde in K\u00f6then (Anhalt) geboren. Als ausgebildeter Mechatroniker bei der Deutschen Bahn, arbeitete er dort in der Wartung und Instandhaltung von Schienen-Baufahrzeugen. Nach einer Fortbildung zum Industriemeister Elektrotechnik wechselte er sp\u00e4ter in die Autoindustrie nach Leipzig. In den folgenden Jahren arbeitete er bei Porsche und BMW. Seit dem Schuljahr 2016\/17 ist er als Fachlehrer f\u00fcr Elektrotechnik an einer Berufsschule t\u00e4tig. Im gleichen Zeitraum begann er, als freier Autor fachliche Texte und Ratgeber zu verfassen."}]}},"_links":{"self":[{"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/posts\/10644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/comments?post=10644"}],"version-history":[{"count":4,"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/posts\/10644\/revisions"}],"predecessor-version":[{"id":18665,"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/posts\/10644\/revisions\/18665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/media\/10645"}],"wp:attachment":[{"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/media?parent=10644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/categories?post=10644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/tags?post=10644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}