{"id":4652,"date":"2023-09-20T09:00:00","date_gmt":"2023-09-20T07:00:00","guid":{"rendered":"https:\/\/www.autoteile-markt.de\/blog\/?p=4652"},"modified":"2025-07-28T10:36:36","modified_gmt":"2025-07-28T08:36:36","slug":"kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen","status":"publish","type":"post","link":"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/","title":{"rendered":"Kupplungssatz beim Auto wechseln &#8211; Schritt-f\u00fcr-Schritt erkl\u00e4rt"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Titelbild-Getriebe-Kupplung-Auto-selbst-wechseln.jpg\"><img  title=\"Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"656\" src=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Titelbild-Getriebe-Kupplung-Auto-selbst-wechseln.jpg\"  alt=\"Titelbild-Getriebe-Kupplung-Auto-selbst-wechseln Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\"  class=\"wp-image-4653\" style=\"object-fit:cover\" srcset=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Titelbild-Getriebe-Kupplung-Auto-selbst-wechseln.jpg 1000w, https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Titelbild-Getriebe-Kupplung-Auto-selbst-wechseln-300x197.jpg 300w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption class=\"wp-element-caption\">\u00a9Foto: vision.si\/depositphotos.com<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Die Autokupplung stellt ein wichtiges Bauteil bei der Kraft\u00fcbertragung vom Motor auf das Getriebe dar. Sie \u00fcbertr\u00e4gt s\u00e4mtliche Beschleunigungskr\u00e4fte und ist daher einer gro\u00dfen Belastung ausgesetzt. Das bedeutet im Umkehrschluss: Mit einer kaputten Getriebekupplung f\u00e4hrt das Auto keinen Meter mehr. Wir verraten in unserer Anleitung, wie die Kupplung funktioniert, warum sie Verschlei\u00df unterliegt und wie Sie sie selbst einen Kupplungssatz erneuern.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/#Aufbau_und_Funktion_der_Fahrzeugkupplung\" >Aufbau und Funktion der Fahrzeugkupplung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/#Welche_Symptome_verursacht_ein_Schaden_an_der_Kupplung\" >Welche Symptome verursacht ein Schaden an der Kupplung?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/#Kupplungssatz_wechseln_Schritt_fuer_Schritt_erklaert\" >Kupplungssatz wechseln Schritt f\u00fcr Schritt erkl\u00e4rt<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/#Kupplungssatz_selber_wechseln_%E2%80%93_Kosten_und_Aufwand\" >Kupplungssatz selber wechseln \u2013 Kosten und Aufwand<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/#Haftungsausschluss\" >Haftungsausschluss<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Aufbau_und_Funktion_der_Fahrzeugkupplung\"><\/span>Aufbau und Funktion der Fahrzeugkupplung<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Jeder Motor mit Benzin oder Diesel hat einen bestimmten Drehzahlbereich, in dem er optimal arbeitet. Das Getriebe sorgt daf\u00fcr, dass sich das Auto bei fast jeder Geschwindigkeit innerhalb dieses Bereichs befindet. Beim Umschalten der G\u00e4nge trennt die Fahrzeugkupplung den angetriebenen Teil des Motors vom Antrieb. Die zweite Funktion ist das Anfahren des Autos. \u00dcber das Kupplungspedal kann der Fahrer die Geschwindigkeit aus dem Stand stufenlos regulieren. Der sogenannte \u201eSchleifpunkt\u201c sollte aber wirklich nur beim Anfahren genutzt werden. Als drittes stellt diese Verbindung noch eine Sollbruchstelle dar, um den Motor und das Getriebe Ihres Autos zu sch\u00fctzen.<\/p>\n\n\n\n<p>Die Autokupplung besteht aus drei wesentlichen Teilen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Schwungrad (heute oft Zweimassenschwungrad)<\/li>\n\n\n\n<li>Kupplungsscheibe (Mitnehmerscheibe)<\/li>\n\n\n\n<li>Druckplatte (Druckscheibe)<\/li>\n<\/ul>\n\n\n\n<p>Das Schwungrad ist mit der Kurbelwelle verbunden. Es hat eine Fl\u00e4che,<br>an der die Kupplungsscheibe anliegt. Die Kupplungsscheibe verf\u00fcgt \u00fcber Reibbel\u00e4ge und stellt die Verbindung durch den Anpressdruck des Kupplungsautomaten her. Dieser Druck wird auf die Druckplatte \u00fcbertragen. Das Ausr\u00fccklager ist f\u00fcr das L\u00f6sen der Verbindung zust\u00e4ndig. Beim Bet\u00e4tigen des<br>Kupplungspedals dr\u00fcckt es auf die Feder des Kupplungsautomaten. Das Auskuppeln<br>l\u00f6st die Kupplungsscheibe um wenige Millimeter vom Schwungrad. L\u00e4sst der Fahrer das Pedal wieder los, dr\u00fcckt die Federkraft Kupplungsscheibe und Schwungrad wieder zusammen.<\/p>\n\n\n<div class=\"row shop-block\">\n    <div class=\"col-sm-6\"><img  title=\"Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\" decoding=\"async\" src=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/kupplung_komplett.jpg\"  alt=\"kupplung_komplett Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\"  class=\"img-responsive\"><\/div>\n    <div class=\"col-sm-6\"><div class=\"block-label\">Kupplungssatz<\/div>\n        <div class=\"block-price\">ab<br \/><span>27,66 \u20ac<\/span><\/div>\n        <div class=\"top15\"><a href=\"\/shop\/kupplung\" class=\"btn btn-amYellow\">zum Shop <span class=\"glyphicon glyphicon-chevron-right\"><\/span><\/a><\/div>\n    <\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Lebensdauer der Autokupplung beim Fahrzeug<\/h3>\n\n\n\n<p>Egal ob Automatik oder Schaltgetriebe: Die Kraft\u00fcbertragung zwischen Kupplungsscheibe und Schwungrad f\u00fchrt zu einem langsamen Verschlei\u00df. Meist sind es die Bel\u00e4ge der Kupplungsscheibe, welche zuerst aufgeben. In der Regel lohnt es sich aufgrund des Aufwands, beim Kupplungswechsel dann gleich Teile wie Druckplatte und Wellendichtringe mit zu erneuern. Hierf\u00fcr gibt es beim H\u00e4ndler einen kompletten Kupplungssatz.<\/p>\n\n\n\n<p>Die Lebensdauer variiert stark zwischen Automatik und Schaltgetriebe. Die meisten Fahrzeugkupplungen beim Auto sind auf eine Lebensdauer von 100.000 und mehr Kilometern ausgelegt. Moderne Kfz mit Automatik erreichen sogar bis zu \u00fcber 300.000 Kilometer. Die Lebensdauer l\u00e4sst sich jedoch positiv und negativ durch das Fahrverhalten beeinflussen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Defekte durch eigenes Fahrverhalten vermeiden<\/h3>\n\n\n\n<p>Es gibt ein paar einfache Ma\u00dfnahmen, mit denen Sie die Lebensdauer Ihrer Fahrzeugkupplung verl\u00e4ngern k\u00f6nnen. Treten Sie das Kupplungspedal beim Schalten immer durch. Ein halb getretenes Pedal kann daf\u00fcr sorgen, dass die Kupplungsscheibe nicht weit genug gel\u00f6st wird und der Schaltvorgang unter Last stattfindet.<\/p>\n\n\n\n<p>W\u00e4hrend der Fahrt und im Leerlauf sollten Sie den Fu\u00df vom Kupplungspedal entfernen. Das verhindert, dass das Pedal minimal gedr\u00fcckt wird. Dadurch l\u00e4uft die Kupplungplatte dauerhaft mit leichtem Schleifpunkt und das Wechseln ist fr\u00fcher n\u00f6tig.<\/p>\n\n\n\n<p>Die dritte Ma\u00dfnahme betrifft das Parken. Bei eingelegtem Gang h\u00e4lt die Kupplungskraft das Auto an Ort und Stelle. Dies sorgt jedoch f\u00fcr eine permanente mechanische Spannung was den Kupplungswechsel dann fr\u00fcher n\u00f6tig macht. Stellen Sie das Auto wo immer m\u00f6glich nur mit Handbremse ab. Vermeiden Sie generell unn\u00f6tiges Kuppeln, das schont die Bel\u00e4ge und verz\u00f6gert das Wechseln.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Welche_Symptome_verursacht_ein_Schaden_an_der_Kupplung\"><\/span>Welche Symptome verursacht ein Schaden an der Kupplung?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Kupplungsdefekte treten meist schleichend auf und k\u00fcndigen sich damit \u00fcber eine lange Zeit an. Achten Sie w\u00e4hrend der Fahrt auf die folgenden Anzeichen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Kupplungspedal reagiert schlecht, Schleifpunkt sehr weit hinten<\/li>\n\n\n\n<li>Auto f\u00e4hrt verz\u00f6gert an<\/li>\n\n\n\n<li>Drehzahl und Geschwindigkeit h\u00e4ngen nicht unmittelbar zusammen<\/li>\n\n\n\n<li>Erh\u00f6hung der Drehzahl beim Bergauffahren<\/li>\n\n\n\n<li>G\u00e4nge lassen sich nur schwer einlegen<\/li>\n\n\n\n<li>ungew\u00f6hnliche Schaltger\u00e4usche<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Wie grenze ich Sch\u00e4den an der Kupplung ein?<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img  title=\"Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Bild3-Verschlissene-Kupplungsscheibe-Schaltgetriebe-Auto.jpg\"  alt=\"Bild3-Verschlissene-Kupplungsscheibe-Schaltgetriebe-Auto Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\"  class=\"wp-image-4655\" style=\"width:250px;height:167px\" srcset=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Bild3-Verschlissene-Kupplungsscheibe-Schaltgetriebe-Auto.jpg 1000w, https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Bild3-Verschlissene-Kupplungsscheibe-Schaltgetriebe-Auto-300x200.jpg 300w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">\u00a9Foto: macor\/depositphotos.com<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Sie k\u00f6nnen eigenst\u00e4ndig eine Diagnose Ihrer Kupplung durchf\u00fchren und beurteilen, ob das Wechseln n\u00f6tig ist. F\u00fchlen Sie zuerst, wie das Kupplungspedal reagiert. Meist kommen hydraulische Komponenten zum Einsatz. Liegt hier ein gro\u00dfes Pedalspiel vor, k\u00f6nnte das an Luft im System und speziell im Geberzylinder liegen. Das Entl\u00fcften des Geberzylinders beseitigt das Problem. Testen Sie die Kupplungskraft nach dem Entl\u00fcften und beobachten Sie, ob das Problem mit der Luft erneut auftritt.<\/p>\n\n\n\n<p><strong>Bei alten Autos<\/strong> kann ein Pedalspiel auch durch das <strong>Nachstellen <\/strong>behoben werden. Moderne Kupplungsautomaten sind selbstnachstellend. Das manuelle Nachstellen durch Mechaniker entf\u00e4llt daher. Sie geben aber auch keine Hinweise auf einen bevorstehenden Defekt. Ein zu gro\u00dfes Spiel stellt auch der T\u00fcv bei der Hauptuntersuchung fest, aber meist bemerkt es der Fahrer als erstes.<\/p>\n\n\n\n<p>Vibriert das Kupplungspedal beim Durchtreten, ist das ein Hinweis auf ein defektes Ausr\u00fccklager. Auch in diesem Fall sollten Sie den Kupplungswechsel vorziehen, da es sonst zu Folgesch\u00e4den kommen kann.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Achtung: Testmethode \u201eAbw\u00fcrgen im Stand\u201c birgt Gefahren<\/h3>\n\n\n\n<p>Manche Foren empfehlen das Abw\u00fcrgen des Autos im Stand auf einem hohen Gang bei hoher Drehzahl zum Kupplungstest. Das \u00fcberlastet jedoch alle Teile der Kupplung und reduziert die verbliebende Lebensdauer. Achten Sie stattdessen auf schleichende Zeichen wie einen gr\u00f6\u00dferen Widerstand des Kupplungspedals oder eine schlechtere Ansprache des Autos beim Anfahren und Beschleunigen. Tritt eines dieser Symptome auf, l\u00e4sst die Kupplungskraft nach und Sie sollten den Tausch des Kupplungssatzes in Erw\u00e4gung ziehen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Kupplungssatz_wechseln_Schritt_fuer_Schritt_erklaert\"><\/span>Kupplungssatz wechseln Schritt f\u00fcr Schritt erkl\u00e4rt<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Sie m\u00fcssen ihre Fahrzeugkupplung wechseln? Es gibt kein gesetzliches Verbot, dies selber zu erledigen. Wir verraten in unserer Anleitung, wie Sie den Kupplungswechsel selbst durchf\u00fchren k\u00f6nnen. Wir beschreiben die \u00fcblichen Schritte, sodass Sie das Wechseln bei den meisten Autos grunds\u00e4tzlich selbst vornehmen k\u00f6nnen. Nehmen Sie, wenn Sie kein Fachmann sind, unbedingt die Hilfe eines Mechanikers in Anspruch.<\/p>\n\n\n\n<p>Informieren Sie sich vor dem Austausch des Kupplungssatzes in geeigneten Quellen \u00fcber Eigenheiten Ihres Autos. F\u00fcr den Austausch ben\u00f6tigen Sie meist eine Vielzahl an Werkzeugen und Hilfsmitteln. Dazu geh\u00f6rt mindestens:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Motorkran oder B\u00f6cke zum Abst\u00fctzen<\/li>\n\n\n\n<li>Satz Gabelschl\u00fcssel<\/li>\n\n\n\n<li>Satz Ringschl\u00fcssel<\/li>\n\n\n\n<li>Satz Steckschl\u00fcssel<\/li>\n\n\n\n<li>Drehmomentschl\u00fcssel<\/li>\n\n\n\n<li>Schraubenzieher<\/li>\n\n\n\n<li>verschiedene Zangen<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">1. Vorbereitung<\/h3>\n\n\n\n<p>W\u00e4hlen Sie f\u00fcr die Reparatur der Kupplung einen geeigneten Ort mit viel Werkzeug und reichlich Platz. Stellen Sie Ihr Auto beispielsweise in einer gut ausgestatteten Werkstatt ab. Stellen Sie einen Motorkran oder B\u00f6cke zum Unterstellen bereit. Sie ben\u00f6tigen diese Werkzeuge sp\u00e4ter, um Motor und Getriebe in Position zu halten. Heben Sie nun das Auto an, idealerweise mit einer Hebeb\u00fchne oder einer vergleichbaren Hubvorrichtung. Der Kupplungswechsel mit Wagenhebern ist grunds\u00e4tzlich m\u00f6glich, aber sehr aufw\u00e4ndig und auch gef\u00e4hrlich.<\/p>\n\n\n\n<p><strong>Klemmen Sie die Batterie ab<\/strong>, so k\u00f6nnen Sie Sch\u00e4den an der Elektroanlage des Autos vermeiden. Trennen Sie dazu die Minusleitung vom Pol der Batterie und sch\u00fctzen Sie die Klemme gegen versehentliches Ber\u00fchren, beispielsweise mit einer Folie. Bei einigen Autos empfiehlt es sich aus Platzgr\u00fcnden, die Batterie komplett auszubauen.<\/p>\n\n\n\n<p>Merken\nSie sich die Position aller Elemente. Das geht am besten, indem Sie\nviele Fotos von allen Elementen machen, welche Sie demontieren. So\nstellen Sie sicher, dass Sie sp\u00e4ter alles wieder an seinem Platz\neinbauen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Schaltgest\u00e4nge und Antriebswelle\ndemontieren<\/h3>\n\n\n\n<p>Trennen Sie die Verbindung zum Schaltgest\u00e4nge. Diese ist entweder geschraubt oder gesplintet. Achten Sie darauf, dass Sie keine Kleinteile verlieren und legen Sie die Teile so, dass Sie deren Position sp\u00e4ter erkennen.<\/p>\n\n\n\n<p>Demontieren Sie nun die Antriebswelle. Daf\u00fcr ben\u00f6tigen Sie einen Steckschl\u00fcssel mit Ratsche, meist auch eine Verl\u00e4ngerung. Bei vielen Autos erreichen Sie die Antriebswelle unproblematisch, wenn das Auto angehoben ist. Eventuell m\u00fcssen Sie vorher andere Teile der Radaufh\u00e4ngung l\u00f6sen oder ausbauen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Weitere Komponenten demontieren<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img  title=\"Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Bild4-Fahrzeug-anheben-und-Schaltgetriebe-freilegen.jpg\"  alt=\"Bild4-Fahrzeug-anheben-und-Schaltgetriebe-freilegen Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\"  class=\"wp-image-4656\" style=\"width:250px;height:167px\" srcset=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Bild4-Fahrzeug-anheben-und-Schaltgetriebe-freilegen.jpg 1000w, https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Bild4-Fahrzeug-anheben-und-Schaltgetriebe-freilegen-300x200.jpg 300w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">\u00a9Foto: andreyuu\/depositphotos.com<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Bauen Sie alle Teile ab, die beim Tauschen des Kupplungssatzes st\u00f6ren k\u00f6nnten. Dazu geh\u00f6ren bei den meisten Fahrzeugen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tachowelle\n\tausbauen\n\t<\/li>\n\n\n\n<li>Anlasser\n\tinklusive Verkabelung abklemmen\n\t<\/li>\n\n\n\n<li>s\u00e4mtliche\n\tKabel am Motorgeh\u00e4use l\u00f6sen, Masse entfernen\n<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">4. Motor anh\u00e4ngen oder st\u00fctzen<\/h3>\n\n\n\n<p>Sie sollten nun alle Teile entfernt haben, damit Sie den kompletten Getriebeblock demontieren k\u00f6nnen. Vorher m\u00fcssen Sie den Motor anh\u00e4ngen oder abst\u00fctzen, damit er beim n\u00e4chsten Schritt nicht abst\u00fcrzt. Nutzen Sie dazu Unterstellbock, Getriebehalter, Motorbr\u00fccke oder Werkstattkran.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5. Trennung vom Motor<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img  title=\"Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Bild5-Getriebe-ausgebaut-Kupplungsautomat-l\u00f6sen.jpg\"  alt=\"Bild5-Getriebe-ausgebaut-Kupplungsautomat-l\u00f6sen Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\"  class=\"wp-image-4657\" style=\"width:250px;height:167px\" srcset=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Bild5-Getriebe-ausgebaut-Kupplungsautomat-l\u00f6sen.jpg 1000w, https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Bild5-Getriebe-ausgebaut-Kupplungsautomat-l\u00f6sen-300x200.jpg 300w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">\u00a9Foto: vision.si\/depositphotos.com<\/figcaption><\/figure>\n<\/div>\n\n\n<p>L\u00f6sen Sie nun alle Schrauben, die Motor und Schaltgetriebe miteinander verbinden. Dies sind meist drei oder<br>vier Schrauben. Eventuell m\u00fcssen Sie nun weitere Teile lockern oder demontieren, da mindestens<br>eine Schraube unterhalb des Motors und schwer zug\u00e4nglich ist.<\/p>\n\n\n\n<p>Sind alle Schrauben gel\u00f6st, sollten Sie das <strong>Getriebe<br>vom Motor trennen<\/strong> k\u00f6nnen. Das erfordert etwas Kraft und Geduld und macht sich h\u00e4ufig mit der Hilfe einer zweiten Person besser. F\u00e4deln Sie das Getriebe aus dem Motorraum und achten Sie darauf, keine Kabel oder Schl\u00e4uche abzuscheren. Das erspart den unn\u00f6tigen Wechsel von intakten Teilen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">6. Position merken<\/h3>\n\n\n\n<p>Sie sollten nun einen freien Blick das Schwungrad haben. Sehen Sie sich die Position der eingebauten Teile genau an. Einige Autos verf\u00fcgen \u00fcber deutliche Markierungen. Wenn m\u00f6glich, machen Sie von jedem Arbeitsschritt ein paar aussagekr\u00e4ftige Fotos. Nach dem Wechseln m\u00fcssen Sie die neuen Teile genau so montieren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">7. Kupplungsteile demontieren<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img  title=\"Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\" loading=\"lazy\" decoding=\"async\" width=\"666\" height=\"999\" src=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Bild6-Schaltgetriebe-ausgebaut-Kupplungsscheibe-und-Schwungrad-entfernen-und-s\u00e4ubern.jpg\"  alt=\"Bild6-Schaltgetriebe-ausgebaut-Kupplungsscheibe-und-Schwungrad-entfernen-und-s\u00e4ubern Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\"  class=\"wp-image-4658\" style=\"width:167px;height:250px\" srcset=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Bild6-Schaltgetriebe-ausgebaut-Kupplungsscheibe-und-Schwungrad-entfernen-und-s\u00e4ubern.jpg 666w, https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Bild6-Schaltgetriebe-ausgebaut-Kupplungsscheibe-und-Schwungrad-entfernen-und-s\u00e4ubern-200x300.jpg 200w\" sizes=\"auto, (max-width: 666px) 100vw, 666px\" \/><figcaption class=\"wp-element-caption\">\u00a9Foto: vision.si\/depositphotos.com<\/figcaption><\/figure>\n<\/div>\n\n\n<p>L\u00f6sen Sie alle Schrauben, die das Schwungrad, die Druckplatte und die Kupplungsscheibe festhalten. Dies sind in der Regel mehrere kleinere Schrauben, die kreisf\u00f6rmig angeordnet sind. Ziehen Sie die Scheiben vorsichtig ab und achten Sie auf die Position der Teile. Das Schwungrad hat meist eine Vorrichtung, welche die Montage nur in einer bestimmten Position erlaubt.<\/p>\n\n\n\n<p>Untersuchen Sie das Schwungrad. Ist es besch\u00e4digt, m\u00fcssen Sie es Wechseln. Achten Sie au\u00dferdem auf \u00d6llecks oder Undichtigkeiten im Bereich der Kupplung. Tritt \u00d6l aus, sollten Sie die Ursache beheben.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">8. Teile ersetzen oder reinigen<\/h3>\n\n\n\n<p>Sehen Sie Ihren neuen Kupplungssatz an und wechseln Sie neu vorhandene Bauteile. S\u00e4ubern Sie alle Teile, die Sie nicht wechseln k\u00f6nnen und daher wiederverwenden m\u00fcssen. Dazu geh\u00f6ren die meisten Schrauben und Dichtringe, das Schwungrad, der Kurbelwellenflansch und das Getriebe. Sie sollten auch <a href=\"\/shop\/kupplung-ausruecklager\">Ausr\u00fcckhebel und Ausr\u00fcckteller untersuchen und bei Bedarf erneuern<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">9. Druckplatte wechseln und ansetzen<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img  title=\"Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\" loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Bild7-Neue-Kupplungsscheibe-in-das-Schaltgetriebe-Auto-einsetzen.jpg\"  alt=\"Bild7-Neue-Kupplungsscheibe-in-das-Schaltgetriebe-Auto-einsetzen Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\"  class=\"wp-image-4659\" style=\"width:250px;height:167px\" srcset=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Bild7-Neue-Kupplungsscheibe-in-das-Schaltgetriebe-Auto-einsetzen.jpg 1000w, https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Bild7-Neue-Kupplungsscheibe-in-das-Schaltgetriebe-Auto-einsetzen-300x200.jpg 300w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">\u00a9Foto: vision.si\/depositphotos.com<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Erneuern und montieren Sie die Druckplatte. Ziehen Sie die Schrauben mit dem angegebenen Drehmoment fest. Achten Sie darauf, den Sicherungsring wieder richtig einzusetzen. Schmieren Sie ein wenig Kupplungsfett auf das Lager in der Mitte und wischen Sie eventuelle Rest ab. Es darf kein \u00fcbersch\u00fcssiges Fett verbleiben, da dieses sonst auf die Kupplungsscheibe gelangen und die Wirkung zerst\u00f6ren k\u00f6nnte.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">10. Schwungrad- und Kupplungsscheiben montieren<\/h3>\n\n\n\n<p>Ersetzen Sie die Kupplungsscheibe und setzen Sie sie zusammen mit dem Schwungrad an. Das Schwungrad passt \u00fcblicherweise nur in einer Position. Achten Sie beim festschrauben darauf, dass die Kupplungsscheibe mittig im Schwungrad sitzt. Halten Sie auch hier wieder das vorgegebene Drehmoment ein und ziehen Sie die Schrauben \u00fcber Kreuz an.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">11. Montage in umgekehrter Reihenfolge<\/h3>\n\n\n\n<p>Nehmen Sie Ihre Fotos zur Hand und f\u00fchren Sie nun alle<br>Schritte der Demontage in genau umgekehrter Reihenfolge aus. Wechseln Sie Teile, die besch\u00e4digt sind oder sich nicht wieder einbauen lassen. Montieren Sie Getriebe, Kupplungsgest\u00e4nge, Starter, Schl\u00e4uche, Leitungen und alle Teile, welche Sie demontiert haben.<\/p>\n\n\n\n<p>Anschlie\u00dfend k\u00f6nnen Sie das Auto starten, kuppeln und pr\u00fcfen, ob das Tauschen den gew\u00fcnschten Erfolg gebracht hat. Testen Sie auch die G\u00e4nge beim Schaltgetriebe. Alles in Ordnung? Dann erf\u00fcllt der neue Kupplungssatz seine Aufgabe.<\/p>\n\n\n\n<div class=\"lyte-wrapper\" title=\"BMW Kupplung wechseln | rutschende Kupplung beim E46 330i Baby M3 G-Power Projekt ( Tutorial )\" style=\"width:640px;max-width:100%;margin:5px auto;\"><div class=\"lyMe hidef\" id=\"WYL_DPYXJrmFwws\" itemprop=\"video\" itemscope itemtype=\"https:\/\/schema.org\/VideoObject\"><div><meta itemprop=\"thumbnailUrl\" content=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FDPYXJrmFwws%2Fmaxresdefault.jpg\" \/><meta itemprop=\"embedURL\" content=\"https:\/\/www.youtube.com\/embed\/DPYXJrmFwws\" \/><meta itemprop=\"duration\" content=\"PT24M35S\" \/><meta itemprop=\"uploadDate\" content=\"2019-08-11T06:00:01Z\" \/><\/div><div id=\"lyte_DPYXJrmFwws\" data-src=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FDPYXJrmFwws%2Fmaxresdefault.jpg\" class=\"pL\"><div class=\"tC\"><div class=\"tT\" itemprop=\"name\">BMW Kupplung wechseln | rutschende Kupplung beim E46 330i Baby M3 G-Power Projekt ( Tutorial )<\/div><\/div><div class=\"play\"><\/div><div class=\"ctrl\"><div class=\"Lctrl\"><\/div><div class=\"Rctrl\"><\/div><\/div><\/div><noscript><a href=\"https:\/\/youtu.be\/DPYXJrmFwws\" rel=\"nofollow\"><img  title=\"Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/plugins\/wp-youtube-lyte\/lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FDPYXJrmFwws%2F0.jpg\"  alt=\"lyteCache.php?origThumbUrl=https%3A%2F%2Fi.ytimg.com%2Fvi%2FDPYXJrmFwws%2F0 Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\"  width=\"640\" height=\"340\" \/><br \/>Dieses Video auf YouTube ansehen<\/a><\/noscript><meta itemprop=\"description\" content=\"\u27a1\ufe0f\u27a1\ufe0fZum Neuen Carly Adapter: https:\/\/bit.ly\/2BXN76z \u27a1\ufe0fHier gibts Rostl\u00f6ser: https:\/\/amzn.to\/31A5XHZ \u27a1\ufe0fHier gibt&#039;s den Kupplungssatz: https:\/\/ebay.to\/2KIh8HN \u27a1\ufe0fHier gibts den Zentrierdorn-Satz: https:\/\/amzn.to\/2KCPqfM Alle Videos zum E46 Baby M3 Projekt: - Der Kauf: https:\/\/www.youtube.com\/watch?v=6BqlxeeMCnU&amp;t=869s - Eingangsmessung: https:\/\/www.youtube.com\/watch?v=_Np-cigH7Qo&amp;t=4s - Einbau des Kompressors: https:\/\/www.youtube.com\/watch?v=G3Bwh8-vcq8&amp;t=2435s - Ausgangsmessung: https:\/\/www.youtube.com\/watch?v=nbNES_tWfX8 - Codieren: https:\/\/www.youtube.com\/watch?v=asGAdOb54jY&amp;t=8s \u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac\u25ac ==Werkstattkosten gespart ? == Unterst\u00fctzt uns: https:\/\/www.paypal.me\/julianundmax == Partner\/Sponsoren == K\u00e4ser Kompressoren: http:\/\/www.kaeser.de\/dein-druckluftspezialist == Partnerwerkst\u00e4tten == Hier findet Ihr eine Liste von Kfz Betrieben die wir empfehlen ! https:\/\/reparaturtutorial.de\/partnerwerkstaetten\/ == Soziale Netzwerke == Facebook: https:\/\/www.facebook.com\/autoreparaturtutorial Instagram: https:\/\/www.instagram.com\/autoreparaturtutorial Twitter: https:\/\/twitter.com\/ARTMadmaxAutoTu Website: https:\/\/reparaturtutorial.de == \u00dcber Uns == Herzlich Willkommen bei Auto Reparatur Tutorial ! Wir hei\u00dfen Julian und Max. Sch\u00f6n dass Ihr eines unserer Videos anseht. Euer Auto hat ein Problem oder ist kaputt und Ihr wollt zudem euren Geldbeutel schonen? Kein Problem ! Hier findet Ihr zu vielen Themen Tutorials, die euch helfen euer Auto oder Motorrad zu reparieren bzw. in Stand zu halten. Auf unserem Kanal findet Ihr eine Vielzahl von Reparaturen: Radlagerwechsel, Spurstange wechseln, Scheinwerfer ein und ausbauen, R\u00fccklichter ein und ausbauen, Bremsfl\u00fcssigkeit wechseln, Bremsenbel\u00e4ge und Bremsscheiben erneuern, Kundendienst, Inspektion, Service, \u00d6lwechsel Motorrad, \u00d6lwechsel Auto, Federn wechseln, Windschutzscheibe Frontscheibe wechseln, defekte Klimaanlage instandsetzen, Z\u00fcndkerzen wechseln, Ventildeckeldichtung wechseln, Freisprecheinrichtung einbauen, Felgen folieren, Agr Ventil reinigen, Auto folieren, Xenonbirnenwechsel, Ventilschaftdichtung wechseln, Injektoren wechseln, egr Ventil deaktivieren und vieles mehr. == Infos zu den Links == Die mit * gekennzeichneten Links sind sogenannte Affiliate-Links, die mit dem Partnerprogramm von Amazon Ebay oder Affili.net verkn\u00fcpft sind. Kommt \u00fcber einen solchen Link ein Einkauf zustande, werde ich mit einer Provision beteiligt. F\u00fcr Dich entstehen dabei keine Mehrkosten. Wo, wann und wie Du ein Produkt kaufst, bleibt nat\u00fcrlich Dir \u00fcberlassen. #autoreparaturtutorial\"><\/div><\/div><div class=\"lL\" style=\"max-width:100%;width:640px;margin:5px auto;\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Kupplungssatz_selber_wechseln_%E2%80%93_Kosten_und_Aufwand\"><\/span>Kupplungssatz selber wechseln \u2013 Kosten und Aufwand<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Der Kupplungssatz beim Schaltgetriebe ist eines der teureren Ersatzteilsets am Auto. Mit unserer Einbauanleitung k\u00f6nnen Sie die Autokupplung an den meisten Fahrzeugen selbst tauschen. Ein neuer Satz kostet im Durchschnitt <strong>zwischen 60 und 300 \u20ac<\/strong>. Die ben\u00f6tigten Werkzeuge sind umfangreich, finden sich aber in einer gut ausgestatteten Werkstatt. Der Aufwand richtet sich stark nach dem Auto, betr\u00e4gt aber meist etliche Stunden.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.autoteile-markt.de\/shop\/kupplung\">Kaufen Sie Ihre Ersatzteile f\u00fcr die Kupplung<\/a> und weitere Ersatzteile bei Autoteile-Markt. Unser Marktplatz mit mehreren hundert Anbietern stellt Autoteile f\u00fcr nahezu jedes Fahrzeug bereit. Mithilfe unserer Suchfunktionen k\u00f6nnen Sie einen Preisvergleich vornehmen und Ihre Ersatzteile g\u00fcnstig kaufen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Was kostet eine neuer Kupplungssatz in der Werkstatt?<\/h3>\n\n\n\n<p>Sie k\u00f6nnen den Kupplungswechsel nat\u00fcrlich auch in einer Werkstatt durchf\u00fchren lassen. Hier m\u00fcssen Sie nat\u00fcrlich tiefer in die Tasche greifen. Die Teile kosten etwas mehr und zus\u00e4tzlich m\u00fcssen Sie die Arbeitszeit verg\u00fcten. Je nach Auto fallen f\u00fcr das Wechseln des Kupplungssatzes in der Werkstatt Gesamtkosten zwischen 700 und 2000 \u20ac an.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Haftungsausschluss\"><\/span>Haftungsausschluss<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Unsere Ratgeber enthalten viele fachliche Informationen rund um das KFZ, die wir sorgf\u00e4ltig zusammengetragen haben. Diese Artikel k\u00f6nnen allerdings die Fachkenntnis eines Spezialisten nicht ersetzen. Autoteile-Markt haftet daher nicht f\u00fcr Sch\u00e4den und Verletzungen, die durch unsachgem\u00e4\u00df ausgef\u00fchrte Reparaturen entstehen. Wir empfehlen grunds\u00e4tzlich, Arbeiten am KFZ nur von einem Fachmann ausf\u00fchren zu lassen.<\/p>\n\n\n<style>#sp-ea-12465 .spcollapsing { height: 0; overflow: hidden; transition-property: height;transition-duration: 300ms;}.sp-easy-accordion-enabled .eap_section_title_12465, body .eap_section_title_12465 { color: #444; margin-bottom:  30px; }#sp-ea-12465.sp-easy-accordion>.sp-ea-single {margin-bottom: 10px; border: 1px solid #e2e2e2; }#sp-ea-12465.sp-easy-accordion>.sp-ea-single>.ea-header a {color: #444;}#sp-ea-12465.sp-easy-accordion>.sp-ea-single>.sp-collapse>.ea-body {background: #fff; color: #444;}#sp-ea-12465.sp-easy-accordion>.sp-ea-single {background: #eee;}#sp-ea-12465.sp-easy-accordion>.sp-ea-single>.ea-header a .ea-expand-icon { float: left; color: #444;font-size: 16px;}<\/style><h2 class=\"eap_section_title eap_section_title_12465\">FAQ \u2013 Kupplungssatz wechseln<\/h2><div id=\"sp_easy_accordion-1700470554\"><div id=\"sp-ea-12465\" class=\"sp-ea-one sp-easy-accordion\" data-ea-active=\"ea-click\" data-ea-mode=\"vertical\" data-preloader=\"\" data-scroll-active-item=\"\" data-offset-to-scroll=\"0\"><div class=\"ea-card ea-expand sp-ea-single\"><h3 class=\"ea-header\"><a class=\"collapsed\" id=\"ea-header-124650\" role=\"button\" data-sptoggle=\"spcollapse\" data-sptarget=\"#collapse124650\" aria-controls=\"collapse124650\" href=\"#\" aria-expanded=\"true\" tabindex=\"0\"><i aria-hidden=\"true\" role=\"presentation\" class=\"ea-expand-icon eap-icon-ea-expand-minus\"><\/i> Wie bemerke ich, wann ein Wechsel des Kupplungssatzes n\u00f6tig ist?<\/a><\/h3><div class=\"sp-collapse spcollapse collapsed show\" id=\"collapse124650\" data-parent=\"#sp-ea-12465\" role=\"region\" aria-labelledby=\"ea-header-124650\"> <div class=\"ea-body\"><p>Ein Schaden an Teilen der Fahrzeugkupplung macht sich durch verschiedene Anzeichen bemerkbar. Beobachten Sie das Auto w\u00e4hrend der Fahrt. Bei bestimmten Symptomen ist der Wechsel n\u00f6tig:<\/p><p><\/p><ul><li style=\"list-style-type: none\"><ul><\/p><li>Kupplungspedal Schleifpunkt versetzt nach hinten<\/li><\/ul><\/li><\/ul><p> <\/p><ul><li style=\"list-style-type: none\"><ul><li>Anfahren geht nur mit Verz\u00f6gerung<\/li><\/ul><\/li><\/ul><p> <\/p><ul><li style=\"list-style-type: none\"><ul><li>Zusammenhang zwischen Drehzahl und Geschwindigkeit gest\u00f6rt<\/li><\/ul><\/li><\/ul><p> <\/p><ul><li style=\"list-style-type: none\"><ul><li>Schaltger\u00e4usche beziehungsweise G\u00e4nge lassen sich nur schwer einlegen<\/li><\/ul><\/li><\/ul><p><\/p><p><\/p><\/div><\/div><\/div><div class=\"ea-card sp-ea-single\"><h3 class=\"ea-header\"><a class=\"collapsed\" id=\"ea-header-124651\" role=\"button\" data-sptoggle=\"spcollapse\" data-sptarget=\"#collapse124651\" aria-controls=\"collapse124651\" href=\"#\" aria-expanded=\"false\" tabindex=\"0\"><i aria-hidden=\"true\" role=\"presentation\" class=\"ea-expand-icon eap-icon-ea-expand-plus\"><\/i> Welche Ausr\u00fcstung ben\u00f6tige ich zum Erneuern des Kupplungssatzes?<\/a><\/h3><div class=\"sp-collapse spcollapse \" id=\"collapse124651\" data-parent=\"#sp-ea-12465\" role=\"region\" aria-labelledby=\"ea-header-124651\"> <div class=\"ea-body\"><p>F\u00fcr den Wechsel des Kupplungssatzes ben\u00f6tigen Sie je nach Auto eine <strong>Vielzahl an Werkzeugen und Hilfsmitteln<\/strong>:<\/p><p><\/p><ul><li style=\"list-style-type: none\"><ul><\/p><li>Motorkran oder St\u00fctzen<\/li><\/ul><\/li><\/ul><p> <\/p><ul><li style=\"list-style-type: none\"><ul><li>Schraubenzieher<\/li><\/ul><\/li><\/ul><p> <\/p><ul><li style=\"list-style-type: none\"><ul><li>verschiedene Zangen<\/li><\/ul><\/li><\/ul><p> <\/p><ul><li style=\"list-style-type: none\"><ul><li>Satz Gabelschl\u00fcssel, Ringschl\u00fcssel, Steckschl\u00fcssel<\/li><\/ul><\/li><\/ul><p> <\/p><ul><li style=\"list-style-type: none\"><ul><li>Drehmomentschl\u00fcssel<\/li><\/ul><\/li><\/ul><p><\/p><p><\/p><\/div><\/div><\/div><div class=\"ea-card sp-ea-single\"><h3 class=\"ea-header\"><a class=\"collapsed\" id=\"ea-header-124652\" role=\"button\" data-sptoggle=\"spcollapse\" data-sptarget=\"#collapse124652\" aria-controls=\"collapse124652\" href=\"#\" aria-expanded=\"false\" tabindex=\"0\"><i aria-hidden=\"true\" role=\"presentation\" class=\"ea-expand-icon eap-icon-ea-expand-plus\"><\/i> Kann ich den Kupplungssatz beim Auto selbstst\u00e4ndig tauschen?<\/a><\/h3><div class=\"sp-collapse spcollapse \" id=\"collapse124652\" data-parent=\"#sp-ea-12465\" role=\"region\" aria-labelledby=\"ea-header-124652\"> <div class=\"ea-body\"><p>Der Kupplungswechsel ist keine Arbeit f\u00fcr Laien ohne fachliche Unterst\u00fctzung. F\u00fchren Sie diese Reparatur nur selbst aus, wenn Sie \u00fcber die <strong>notwendige Fachkenntnis<\/strong> verf\u00fcgen oder einen Fachmann zur Hilfe holen k\u00f6nnen. Andernfalls riskieren Sie Verletzungen und Sch\u00e4den bei der Reparatur oder eine Kupplung ohne Funktion.<\/p><\/div><\/div><\/div><script type=\"application\/ld+json\">{ \"@context\": \"https:\/\/schema.org\", \"@type\": \"FAQPage\", \"@id\": \"sp-ea-schema-12465-6a04c147d0af1\", \"mainEntity\": [{ \"@type\": \"Question\", \"name\": \"Wie bemerke ich, wann ein Wechsel des Kupplungssatzes n\u00f6tig ist?\", \"acceptedAnswer\": { \"@type\": \"Answer\", \"text\": \"Ein Schaden an Teilen der Fahrzeugkupplung macht sich durch verschiedene Anzeichen bemerkbar. Beobachten Sie das Auto w\u00e4hrend der Fahrt. Bei bestimmten Symptomen ist der Wechsel n\u00f6tig:<ul><li><ul><li>Kupplungspedal Schleifpunkt versetzt nach hinten<\/li><\/ul><\/li><\/ul><ul><li><ul><li>Anfahren geht nur mit Verz\u00f6gerung<\/li><\/ul><\/li><\/ul><ul><li><ul><li>Zusammenhang zwischen Drehzahl und Geschwindigkeit gest\u00f6rt<\/li><\/ul><\/li><\/ul><ul><li><ul><li>Schaltger\u00e4usche beziehungsweise G\u00e4nge lassen sich nur schwer einlegen<\/li><\/ul><\/li><\/ul>\" } },{ \"@type\": \"Question\", \"name\": \"Welche Ausr\u00fcstung ben\u00f6tige ich zum Erneuern des Kupplungssatzes?\", \"acceptedAnswer\": { \"@type\": \"Answer\", \"text\": \"F\u00fcr den Wechsel des Kupplungssatzes ben\u00f6tigen Sie je nach Auto eine<strong>Vielzahl an Werkzeugen und Hilfsmitteln<\/strong>:<ul><li><ul><li>Motorkran oder St\u00fctzen<\/li><\/ul><\/li><\/ul><ul><li><ul><li>Schraubenzieher<\/li><\/ul><\/li><\/ul><ul><li><ul><li>verschiedene Zangen<\/li><\/ul><\/li><\/ul><ul><li><ul><li>Satz Gabelschl\u00fcssel, Ringschl\u00fcssel, Steckschl\u00fcssel<\/li><\/ul><\/li><\/ul><ul><li><ul><li>Drehmomentschl\u00fcssel<\/li><\/ul><\/li><\/ul>\" } },{ \"@type\": \"Question\", \"name\": \"Kann ich den Kupplungssatz beim Auto selbstst\u00e4ndig tauschen?\", \"acceptedAnswer\": { \"@type\": \"Answer\", \"text\": \"Der Kupplungswechsel ist keine Arbeit f\u00fcr Laien ohne fachliche Unterst\u00fctzung. F\u00fchren Sie diese Reparatur nur selbst aus, wenn Sie \u00fcber die<strong>notwendige Fachkenntnis<\/strong>verf\u00fcgen oder einen Fachmann zur Hilfe holen k\u00f6nnen. Andernfalls riskieren Sie Verletzungen und Sch\u00e4den bei der Reparatur oder eine Kupplung ohne Funktion.\" } }] }<\/script><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"Ihr Auto beschleunigt tr\u00e4ge oder der Gangwechsel geht schlecht? Sparen Sie Kosten und wechseln sie den Kupplungssatz mit unserer Anleitung selbst.\n... <br \/><a class=\"read-more\" href=\"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/\">Weiterlesen<\/a>","protected":false},"author":6,"featured_media":4653,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-4652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ratgeber"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt<\/title>\n<meta name=\"description\" content=\"Ihr Auto beschleunigt tr\u00e4ge oder der Gangwechsel geht schlecht? Sparen Sie Kosten und wechseln sie den Kupplungssatz mit unserer Anleitung selbst.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt\" \/>\n<meta property=\"og:description\" content=\"Ihr Auto beschleunigt tr\u00e4ge oder der Gangwechsel geht schlecht? Sparen Sie Kosten und wechseln sie den Kupplungssatz mit unserer Anleitung selbst.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/\" \/>\n<meta property=\"og:site_name\" content=\"Autoteile-Markt.de Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AutoteileMarktde\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-20T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-28T08:36:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Titelbild-Getriebe-Kupplung-Auto-selbst-wechseln.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"656\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"F. Selleng\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@autoteilemarkt\" \/>\n<meta name=\"twitter:site\" content=\"@autoteilemarkt\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"F. Selleng\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"13\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt","description":"Ihr Auto beschleunigt tr\u00e4ge oder der Gangwechsel geht schlecht? Sparen Sie Kosten und wechseln sie den Kupplungssatz mit unserer Anleitung selbst.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/","og_locale":"de_DE","og_type":"article","og_title":"Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt","og_description":"Ihr Auto beschleunigt tr\u00e4ge oder der Gangwechsel geht schlecht? Sparen Sie Kosten und wechseln sie den Kupplungssatz mit unserer Anleitung selbst.","og_url":"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/","og_site_name":"Autoteile-Markt.de Blog","article_publisher":"https:\/\/www.facebook.com\/AutoteileMarktde\/","article_published_time":"2023-09-20T07:00:00+00:00","article_modified_time":"2025-07-28T08:36:36+00:00","og_image":[{"width":1000,"height":656,"url":"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Titelbild-Getriebe-Kupplung-Auto-selbst-wechseln.jpg","type":"image\/jpeg"}],"author":"F. Selleng","twitter_card":"summary_large_image","twitter_creator":"@autoteilemarkt","twitter_site":"@autoteilemarkt","twitter_misc":{"Written by":"F. Selleng","Est. reading time":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/#article","isPartOf":{"@id":"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/"},"author":{"name":"F. Selleng","@id":"https:\/\/www.autoteile-markt.de\/blog\/#\/schema\/person\/cea0595ff01d1a3de7b2f838d87645cd"},"headline":"Kupplungssatz beim Auto wechseln &#8211; Schritt-f\u00fcr-Schritt erkl\u00e4rt","datePublished":"2023-09-20T07:00:00+00:00","dateModified":"2025-07-28T08:36:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/"},"wordCount":2146,"image":{"@id":"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Titelbild-Getriebe-Kupplung-Auto-selbst-wechseln.jpg","articleSection":["Ratgeber"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/","url":"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/","name":"Kupplungssatz beim Auto wechseln - Schritt-f\u00fcr-Schritt erkl\u00e4rt","isPartOf":{"@id":"https:\/\/www.autoteile-markt.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/#primaryimage"},"image":{"@id":"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Titelbild-Getriebe-Kupplung-Auto-selbst-wechseln.jpg","datePublished":"2023-09-20T07:00:00+00:00","dateModified":"2025-07-28T08:36:36+00:00","author":{"@id":"https:\/\/www.autoteile-markt.de\/blog\/#\/schema\/person\/cea0595ff01d1a3de7b2f838d87645cd"},"description":"Ihr Auto beschleunigt tr\u00e4ge oder der Gangwechsel geht schlecht? Sparen Sie Kosten und wechseln sie den Kupplungssatz mit unserer Anleitung selbst.","breadcrumb":{"@id":"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/#primaryimage","url":"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Titelbild-Getriebe-Kupplung-Auto-selbst-wechseln.jpg","contentUrl":"https:\/\/www.autoteile-markt.de\/blog\/wp-content\/uploads\/2020\/03\/Titelbild-Getriebe-Kupplung-Auto-selbst-wechseln.jpg","width":1000,"height":656,"caption":"\u00a9Foto: vision.si\/depositphotos.com"},{"@type":"BreadcrumbList","@id":"https:\/\/www.autoteile-markt.de\/blog\/kupplungssatzwechsel-ratgeber-anleitung-zum-selber-tauschen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.autoteile-markt.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Kupplungssatz beim Auto wechseln &#8211; Schritt-f\u00fcr-Schritt erkl\u00e4rt"}]},{"@type":"WebSite","@id":"https:\/\/www.autoteile-markt.de\/blog\/#website","url":"https:\/\/www.autoteile-markt.de\/blog\/","name":"Autoteile-Markt.de Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.autoteile-markt.de\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.autoteile-markt.de\/blog\/#\/schema\/person\/cea0595ff01d1a3de7b2f838d87645cd","name":"F. Selleng","description":"F. Selleng wurde in K\u00f6then (Anhalt) geboren. Als ausgebildeter Mechatroniker bei der Deutschen Bahn, arbeitete er dort in der Wartung und Instandhaltung von Schienen-Baufahrzeugen. Nach einer Fortbildung zum Industriemeister Elektrotechnik wechselte er sp\u00e4ter in die Autoindustrie nach Leipzig. In den folgenden Jahren arbeitete er bei Porsche und BMW. Seit dem Schuljahr 2016\/17 ist er als Fachlehrer f\u00fcr Elektrotechnik an einer Berufsschule t\u00e4tig. Im gleichen Zeitraum begann er, als freier Autor fachliche Texte und Ratgeber zu verfassen."}]}},"_links":{"self":[{"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/posts\/4652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/comments?post=4652"}],"version-history":[{"count":46,"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/posts\/4652\/revisions"}],"predecessor-version":[{"id":18392,"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/posts\/4652\/revisions\/18392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/media\/4653"}],"wp:attachment":[{"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/media?parent=4652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/categories?post=4652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.autoteile-markt.de\/blog\/wp-json\/wp\/v2\/tags?post=4652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}